{"id":257,"count":37,"description":"","link":"https:\/\/casadisposa.gr\/en\/product-category\/seasonal\/gifts\/gifts_mom_en\/","name":"Gifts for Mom","slug":"gifts_mom_en","taxonomy":"product_cat","parent":248,"meta":[],"menu_order":60,"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Gifts for Mom | Casadisposa<\/title>\n<meta name=\"description\" content=\"Casadisposa | Casa di Sposa. Wedding &amp; baptism items in Karpenisi, Greece. Top quality. Decoration, seasonal hand-made gifts. Tel.: +30 2237080119.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadisposa.gr\/en\/product-category\/seasonal\/gifts\/gifts_mom_en\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Gifts for Mom | Casadisposa\" \/>\n<meta property=\"og:description\" content=\"Casadisposa | Casa di Sposa. Wedding &amp; baptism items in Karpenisi, Greece. Top quality. Decoration, seasonal hand-made gifts. Tel.: +30 2237080119.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadisposa.gr\/en\/product-category\/seasonal\/gifts\/gifts_mom_en\/\" \/>\n<meta property=\"og:site_name\" content=\"Casadisposa\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/product-category\\\/seasonal\\\/gifts\\\/gifts_mom_en\\\/\",\"url\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/product-category\\\/seasonal\\\/gifts\\\/gifts_mom_en\\\/\",\"name\":\"Gifts for Mom | Casadisposa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/#website\"},\"description\":\"Casadisposa | Casa di Sposa. Wedding & baptism items in Karpenisi, Greece. Top quality. Decoration, seasonal hand-made gifts. Tel.: +30 2237080119.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/product-category\\\/seasonal\\\/gifts\\\/gifts_mom_en\\\/#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/product-category\\\/seasonal\\\/gifts\\\/gifts_mom_en\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SEASONAL\",\"item\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/product-category\\\/seasonal\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Gifts\",\"item\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/product-category\\\/seasonal\\\/gifts\\\/\"},{\"@type\":\"ListItem\",\"position\":4,\"name\":\"Gifts for Mom\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/\",\"name\":\"Casadisposa\",\"description\":\"\u03a3\u03c4\u03bf\u03bb\u03b9\u03c3\u03bc\u03cc\u03c2 - \u0394\u03b9\u03b1\u03ba\u03cc\u03c3\u03bc\u03b7\u03c3\u03b7 - \u0395\u03c0\u03bf\u03c7\u03b9\u03b1\u03ba\u03ac \u03c7\u03b5\u03b9\u03c1\u03bf\u03c0\u03bf\u03af\u03b7\u03c4\u03b1\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/#organization\",\"name\":\"Casa di Sposa\",\"url\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/casadisposa.gr\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-500px.jpg\",\"contentUrl\":\"https:\\\/\\\/casadisposa.gr\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-500px.jpg\",\"width\":500,\"height\":341,\"caption\":\"Casa di Sposa\"},\"image\":{\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Gifts for Mom | Casadisposa","description":"Casadisposa | Casa di Sposa. Wedding & baptism items in Karpenisi, Greece. Top quality. Decoration, seasonal hand-made gifts. Tel.: +30 2237080119.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadisposa.gr\/en\/product-category\/seasonal\/gifts\/gifts_mom_en\/","og_locale":"en_US","og_type":"article","og_title":"Gifts for Mom | Casadisposa","og_description":"Casadisposa | Casa di Sposa. Wedding & baptism items in Karpenisi, Greece. Top quality. Decoration, seasonal hand-made gifts. Tel.: +30 2237080119.","og_url":"https:\/\/casadisposa.gr\/en\/product-category\/seasonal\/gifts\/gifts_mom_en\/","og_site_name":"Casadisposa","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/casadisposa.gr\/en\/product-category\/seasonal\/gifts\/gifts_mom_en\/","url":"https:\/\/casadisposa.gr\/en\/product-category\/seasonal\/gifts\/gifts_mom_en\/","name":"Gifts for Mom | Casadisposa","isPartOf":{"@id":"https:\/\/casadisposa.gr\/en\/#website"},"description":"Casadisposa | Casa di Sposa. Wedding & baptism items in Karpenisi, Greece. Top quality. Decoration, seasonal hand-made gifts. Tel.: +30 2237080119.","breadcrumb":{"@id":"https:\/\/casadisposa.gr\/en\/product-category\/seasonal\/gifts\/gifts_mom_en\/#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/casadisposa.gr\/en\/product-category\/seasonal\/gifts\/gifts_mom_en\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadisposa.gr\/en\/"},{"@type":"ListItem","position":2,"name":"SEASONAL","item":"https:\/\/casadisposa.gr\/en\/product-category\/seasonal\/"},{"@type":"ListItem","position":3,"name":"Gifts","item":"https:\/\/casadisposa.gr\/en\/product-category\/seasonal\/gifts\/"},{"@type":"ListItem","position":4,"name":"Gifts for Mom"}]},{"@type":"WebSite","@id":"https:\/\/casadisposa.gr\/en\/#website","url":"https:\/\/casadisposa.gr\/en\/","name":"Casadisposa","description":"\u03a3\u03c4\u03bf\u03bb\u03b9\u03c3\u03bc\u03cc\u03c2 - \u0394\u03b9\u03b1\u03ba\u03cc\u03c3\u03bc\u03b7\u03c3\u03b7 - \u0395\u03c0\u03bf\u03c7\u03b9\u03b1\u03ba\u03ac \u03c7\u03b5\u03b9\u03c1\u03bf\u03c0\u03bf\u03af\u03b7\u03c4\u03b1","publisher":{"@id":"https:\/\/casadisposa.gr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadisposa.gr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/casadisposa.gr\/en\/#organization","name":"Casa di Sposa","url":"https:\/\/casadisposa.gr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casadisposa.gr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/casadisposa.gr\/wp-content\/uploads\/2021\/09\/logo-500px.jpg","contentUrl":"https:\/\/casadisposa.gr\/wp-content\/uploads\/2021\/09\/logo-500px.jpg","width":500,"height":341,"caption":"Casa di Sposa"},"image":{"@id":"https:\/\/casadisposa.gr\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/casadisposa.gr\/en\/wp-json\/wp\/v2\/product_cat\/257","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadisposa.gr\/en\/wp-json\/wp\/v2\/product_cat"}],"about":[{"href":"https:\/\/casadisposa.gr\/en\/wp-json\/wp\/v2\/taxonomies\/product_cat"}],"up":[{"embeddable":true,"href":"https:\/\/casadisposa.gr\/en\/wp-json\/wp\/v2\/product_cat\/248"}],"wp:post_type":[{"href":"https:\/\/casadisposa.gr\/en\/wp-json\/wp\/v2\/product?product_cat=257"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}