{"id":15337,"date":"2023-02-08T16:40:47","date_gmt":"2023-02-08T14:42:10","guid":{"rendered":"https:\/\/casadisposa.gr\/product\/sweet-kisses\/"},"modified":"2023-02-13T18:30:38","modified_gmt":"2023-02-13T16:30:38","slug":"sweet-kisses","status":"publish","type":"product","link":"https:\/\/casadisposa.gr\/en\/product\/sweet-kisses\/","title":{"rendered":"&#8221;Sweet Kisses&#8221;"},"content":{"rendered":"<p style=\"text-align: center\">&#8220;kiss&#8221; heart pillow with minnie &amp; mickey print and &#8220;i love you&#8221; message<\/p>\n<p style=\"text-align: center\">Dimension: 42cm*32cm<\/p>\n","protected":false},"excerpt":{"rendered":"<p style=\"text-align: center\">&#8220;kiss&#8221; heart pillow<\/p>\n","protected":false},"featured_media":15330,"template":"","meta":[],"product_brand":[],"product_cat":[178,324],"product_tag":[],"class_list":{"0":"post-15337","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-seasonal","7":"product_cat-valentines-gifts-en","9":"first","10":"instock","11":"sale","12":"shipping-taxable","13":"purchasable","14":"product-type-simple"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>&#039;&#039;Sweet Kisses&#039;&#039; | Casadisposa<\/title>\n<meta name=\"description\" content=\"&#039;&#039;Sweet Kisses&#039;&#039; | Casa di Sposa. Wedding &amp; baptism items in Karpenisi, Greece. Top quality. Decoration, seasonal hand-made gifts. Tel.: +30 2237080119\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/casadisposa.gr\/en\/product\/sweet-kisses\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&#039;&#039;Sweet Kisses&#039;&#039; | Casadisposa\" \/>\n<meta property=\"og:description\" content=\"&#039;&#039;Sweet Kisses&#039;&#039; | Casa di Sposa. Wedding &amp; baptism items in Karpenisi, Greece. Top quality. Decoration, seasonal hand-made gifts. Tel.: +30 2237080119\" \/>\n<meta property=\"og:url\" content=\"https:\/\/casadisposa.gr\/en\/product\/sweet-kisses\/\" \/>\n<meta property=\"og:site_name\" content=\"Casadisposa\" \/>\n<meta property=\"article:modified_time\" content=\"2023-02-13T16:30:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/casadisposa.gr\/wp-content\/uploads\/2023\/02\/IMG_5568.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"1536\" \/>\n\t<meta property=\"og:image:height\" content=\"2048\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/product\\\/sweet-kisses\\\/\",\"url\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/product\\\/sweet-kisses\\\/\",\"name\":\"''Sweet Kisses'' | Casadisposa\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/product\\\/sweet-kisses\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/product\\\/sweet-kisses\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/casadisposa.gr\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/IMG_5568.jpeg\",\"datePublished\":\"2023-02-08T14:42:10+00:00\",\"dateModified\":\"2023-02-13T16:30:38+00:00\",\"description\":\"''Sweet Kisses'' | Casa di Sposa. Wedding & baptism items in Karpenisi, Greece. Top quality. Decoration, seasonal hand-made gifts. Tel.: +30 2237080119\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/product\\\/sweet-kisses\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/casadisposa.gr\\\/en\\\/product\\\/sweet-kisses\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/product\\\/sweet-kisses\\\/#primaryimage\",\"url\":\"https:\\\/\\\/casadisposa.gr\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/IMG_5568.jpeg\",\"contentUrl\":\"https:\\\/\\\/casadisposa.gr\\\/wp-content\\\/uploads\\\/2023\\\/02\\\/IMG_5568.jpeg\",\"width\":1536,\"height\":2048,\"caption\":\"IMG 5568\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/product\\\/sweet-kisses\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"SHOP\",\"item\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/shop-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"&#8221;Sweet Kisses&#8221;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/\",\"name\":\"Casadisposa\",\"description\":\"\u03a3\u03c4\u03bf\u03bb\u03b9\u03c3\u03bc\u03cc\u03c2 - \u0394\u03b9\u03b1\u03ba\u03cc\u03c3\u03bc\u03b7\u03c3\u03b7 - \u0395\u03c0\u03bf\u03c7\u03b9\u03b1\u03ba\u03ac \u03c7\u03b5\u03b9\u03c1\u03bf\u03c0\u03bf\u03af\u03b7\u03c4\u03b1\",\"publisher\":{\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/#organization\",\"name\":\"Casa di Sposa\",\"url\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/casadisposa.gr\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-500px.jpg\",\"contentUrl\":\"https:\\\/\\\/casadisposa.gr\\\/wp-content\\\/uploads\\\/2021\\\/09\\\/logo-500px.jpg\",\"width\":500,\"height\":341,\"caption\":\"Casa di Sposa\"},\"image\":{\"@id\":\"https:\\\/\\\/casadisposa.gr\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"''Sweet Kisses'' | Casadisposa","description":"''Sweet Kisses'' | Casa di Sposa. Wedding & baptism items in Karpenisi, Greece. Top quality. Decoration, seasonal hand-made gifts. Tel.: +30 2237080119","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/casadisposa.gr\/en\/product\/sweet-kisses\/","og_locale":"en_US","og_type":"article","og_title":"''Sweet Kisses'' | Casadisposa","og_description":"''Sweet Kisses'' | Casa di Sposa. Wedding & baptism items in Karpenisi, Greece. Top quality. Decoration, seasonal hand-made gifts. Tel.: +30 2237080119","og_url":"https:\/\/casadisposa.gr\/en\/product\/sweet-kisses\/","og_site_name":"Casadisposa","article_modified_time":"2023-02-13T16:30:38+00:00","og_image":[{"width":1536,"height":2048,"url":"https:\/\/casadisposa.gr\/wp-content\/uploads\/2023\/02\/IMG_5568.jpeg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/casadisposa.gr\/en\/product\/sweet-kisses\/","url":"https:\/\/casadisposa.gr\/en\/product\/sweet-kisses\/","name":"''Sweet Kisses'' | Casadisposa","isPartOf":{"@id":"https:\/\/casadisposa.gr\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/casadisposa.gr\/en\/product\/sweet-kisses\/#primaryimage"},"image":{"@id":"https:\/\/casadisposa.gr\/en\/product\/sweet-kisses\/#primaryimage"},"thumbnailUrl":"https:\/\/casadisposa.gr\/wp-content\/uploads\/2023\/02\/IMG_5568.jpeg","datePublished":"2023-02-08T14:42:10+00:00","dateModified":"2023-02-13T16:30:38+00:00","description":"''Sweet Kisses'' | Casa di Sposa. Wedding & baptism items in Karpenisi, Greece. Top quality. Decoration, seasonal hand-made gifts. Tel.: +30 2237080119","breadcrumb":{"@id":"https:\/\/casadisposa.gr\/en\/product\/sweet-kisses\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/casadisposa.gr\/en\/product\/sweet-kisses\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casadisposa.gr\/en\/product\/sweet-kisses\/#primaryimage","url":"https:\/\/casadisposa.gr\/wp-content\/uploads\/2023\/02\/IMG_5568.jpeg","contentUrl":"https:\/\/casadisposa.gr\/wp-content\/uploads\/2023\/02\/IMG_5568.jpeg","width":1536,"height":2048,"caption":"IMG 5568"},{"@type":"BreadcrumbList","@id":"https:\/\/casadisposa.gr\/en\/product\/sweet-kisses\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/casadisposa.gr\/en\/"},{"@type":"ListItem","position":2,"name":"SHOP","item":"https:\/\/casadisposa.gr\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"&#8221;Sweet Kisses&#8221;"}]},{"@type":"WebSite","@id":"https:\/\/casadisposa.gr\/en\/#website","url":"https:\/\/casadisposa.gr\/en\/","name":"Casadisposa","description":"\u03a3\u03c4\u03bf\u03bb\u03b9\u03c3\u03bc\u03cc\u03c2 - \u0394\u03b9\u03b1\u03ba\u03cc\u03c3\u03bc\u03b7\u03c3\u03b7 - \u0395\u03c0\u03bf\u03c7\u03b9\u03b1\u03ba\u03ac \u03c7\u03b5\u03b9\u03c1\u03bf\u03c0\u03bf\u03af\u03b7\u03c4\u03b1","publisher":{"@id":"https:\/\/casadisposa.gr\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/casadisposa.gr\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/casadisposa.gr\/en\/#organization","name":"Casa di Sposa","url":"https:\/\/casadisposa.gr\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/casadisposa.gr\/en\/#\/schema\/logo\/image\/","url":"https:\/\/casadisposa.gr\/wp-content\/uploads\/2021\/09\/logo-500px.jpg","contentUrl":"https:\/\/casadisposa.gr\/wp-content\/uploads\/2021\/09\/logo-500px.jpg","width":500,"height":341,"caption":"Casa di Sposa"},"image":{"@id":"https:\/\/casadisposa.gr\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/casadisposa.gr\/en\/wp-json\/wp\/v2\/product\/15337","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/casadisposa.gr\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/casadisposa.gr\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/casadisposa.gr\/en\/wp-json\/wp\/v2\/media\/15330"}],"wp:attachment":[{"href":"https:\/\/casadisposa.gr\/en\/wp-json\/wp\/v2\/media?parent=15337"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/casadisposa.gr\/en\/wp-json\/wp\/v2\/product_brand?post=15337"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/casadisposa.gr\/en\/wp-json\/wp\/v2\/product_cat?post=15337"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/casadisposa.gr\/en\/wp-json\/wp\/v2\/product_tag?post=15337"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}